{"id":1112,"date":"2021-06-29T08:05:06","date_gmt":"2021-06-29T08:05:06","guid":{"rendered":"https:\/\/cataccounting.ap5cnyhy-liquidwebsites.com\/privacy-statement\/"},"modified":"2025-01-13T09:44:35","modified_gmt":"2025-01-13T09:44:35","slug":"privacy-statement","status":"publish","type":"page","link":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/","title":{"rendered":"Privacy Statement"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1112\" class=\"elementor elementor-1112\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41d0ada elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41d0ada\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dc2bf0\" data-id=\"0dc2bf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ec321a elementor-widget elementor-widget-spacer\" data-id=\"9ec321a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a6833e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0a6833e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-31665a0\" data-id=\"31665a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ebc22c elementor-widget elementor-widget-image\" data-id=\"3ebc22c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"657\" height=\"823\" src=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png\" class=\"attachment-full size-full wp-image-1113\" alt=\"\" srcset=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png 657w, https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29-239x300.png 239w\" sizes=\"(max-width: 657px) 100vw, 657px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-363cad1 head-box-testimo-priv elementor-widget elementor-widget-heading\" data-id=\"363cad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dichiarazione di riservatezza\/ Privacy<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-713dd49 box-testimo-priv box-testimo-priv-it\" data-id=\"713dd49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7c394a elementor-widget elementor-widget-text-editor\" data-id=\"e7c394a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"privacy-statement-layout\">\n<h2>Dichiarazione di riservatezza\/ Privacy<\/h2>\n<h3>Consideriamo la privacy e la sicurezza delle informazioni del nostro cliente molto seriamente.<br>Se si sceglie di affidare a noi tutte le informazioni personali, come l\u2019indirizzo e-mail, nome, indirizzo, o codice postale, oppure un numero di contatto telefonico, faremo in modo che queste informazioni non saranno mai condivisi con terze parti senza il vostro permesso.<\/h3>\n<h3><span style=\"color: #707070;\">\u00c8 possibile rimuovere permanentemente i dati dal nostro database in qualsiasi momento, oppure potrete chiedere che noi lo facciamo per vostro conto.<\/span><\/h3>\n<h3><span style=\"color: #707070;\">Non abusiamo mai di liste e-mail e non condivideremo mai il tuo indirizzo e-mail con nessuno.<\/span><\/h3><h3><span style=\"color: #707070;\">Se si e\u2019 scelto di ricevere qualsiasi delle nostre informative potremmo, oltre a queste, contattarvi occasionalmente con delle offerte speciali disponibili solo per i clienti registrati. Tuttavia, tali offerte saranno rare e genuine.<\/span>\n    <br><span style=\"color: #707070;\">Tuttavia potrete scegliere in qualsiasi momento di non ricevere tali offerte, se lo desiderate.<\/span><\/h3>\n    <h3><span style=\"color: #707070;\">I dati sono memorizzati in piena conformit\u00e0 con i requisiti per la protezione della registrazione dati .<\/span><br><span style=\"color: #707070;\">Se avete qualsiasi domanda riguardante la privacy o la sicurezza delle informazioni sui vostri dati personali, non esitate a contattarci su:<\/span><br><a style=\"color: #096eb1;\" href=\"mailto:thananan@accounting-tax.co.th\">thananan@accounting-tax.co.th<\/a><\/h3>                              \n <\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d067e72 box-about-us\" data-id=\"d067e72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d5fb75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d5fb75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17b2e13\" data-id=\"17b2e13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c36595 elementor-widget elementor-widget-spacer\" data-id=\"5c36595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dichiarazione di riservatezza\/ Privacy Dichiarazione di riservatezza\/ Privacy Consideriamo la privacy e la sicurezza delle informazioni del nostro cliente molto seriamente.Se si sceglie di affidare a noi tutte le informazioni personali, come l\u2019indirizzo e-mail, nome, indirizzo, o codice postale, oppure un numero di contatto telefonico, faremo in modo che queste informazioni non saranno mai condivisi con terze parti senza il vostro permesso. \u00c8 possibile rimuovere permanentemente i dati dal nostro database in qualsiasi momento, oppure potrete chiedere che noi lo facciamo per vostro conto. Non abusiamo mai di liste e-mail e non condivideremo mai il tuo indirizzo e-mail con nessuno. Se si e\u2019 scelto di ricevere qualsiasi delle nostre informative potremmo, oltre a queste, contattarvi occasionalmente con delle offerte speciali disponibili solo per i clienti registrati. Tuttavia, tali offerte saranno rare e genuine. Tuttavia potrete scegliere in qualsiasi momento di non ricevere tali offerte, se lo desiderate. I dati sono&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1112","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Statement - CATAccounting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Statement - CATAccounting\" \/>\n<meta property=\"og:description\" content=\"Dichiarazione di riservatezza\/ Privacy Dichiarazione di riservatezza\/ Privacy Consideriamo la privacy e la sicurezza delle informazioni del nostro cliente molto seriamente.Se si sceglie di affidare a noi tutte le informazioni personali, come l\u2019indirizzo e-mail, nome, indirizzo, o codice postale, oppure un numero di contatto telefonico, faremo in modo che queste informazioni non saranno mai condivisi con terze parti senza il vostro permesso. \u00c8 possibile rimuovere permanentemente i dati dal nostro database in qualsiasi momento, oppure potrete chiedere che noi lo facciamo per vostro conto. Non abusiamo mai di liste e-mail e non condivideremo mai il tuo indirizzo e-mail con nessuno. Se si e\u2019 scelto di ricevere qualsiasi delle nostre informative potremmo, oltre a queste, contattarvi occasionalmente con delle offerte speciali disponibili solo per i clienti registrati. Tuttavia, tali offerte saranno rare e genuine. Tuttavia potrete scegliere in qualsiasi momento di non ricevere tali offerte, se lo desiderate. I dati sono&hellip;  Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/\" \/>\n<meta property=\"og:site_name\" content=\"CATAccounting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T09:44:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/\",\"name\":\"Privacy Statement - CATAccounting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-29.png\",\"datePublished\":\"2021-06-29T08:05:06+00:00\",\"dateModified\":\"2025-01-13T09:44:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-29.png\",\"contentUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-29.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/privacy-statement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Statement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\",\"name\":\"CATAccounting\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#organization\",\"name\":\"CATAccounting\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-logo-original-white.png\",\"contentUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-logo-original-white.png\",\"width\":361,\"height\":220,\"caption\":\"CATAccounting\"},\"image\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Statement - CATAccounting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Statement - CATAccounting","og_description":"Dichiarazione di riservatezza\/ Privacy Dichiarazione di riservatezza\/ Privacy Consideriamo la privacy e la sicurezza delle informazioni del nostro cliente molto seriamente.Se si sceglie di affidare a noi tutte le informazioni personali, come l\u2019indirizzo e-mail, nome, indirizzo, o codice postale, oppure un numero di contatto telefonico, faremo in modo che queste informazioni non saranno mai condivisi con terze parti senza il vostro permesso. \u00c8 possibile rimuovere permanentemente i dati dal nostro database in qualsiasi momento, oppure potrete chiedere che noi lo facciamo per vostro conto. Non abusiamo mai di liste e-mail e non condivideremo mai il tuo indirizzo e-mail con nessuno. Se si e\u2019 scelto di ricevere qualsiasi delle nostre informative potremmo, oltre a queste, contattarvi occasionalmente con delle offerte speciali disponibili solo per i clienti registrati. Tuttavia, tali offerte saranno rare e genuine. Tuttavia potrete scegliere in qualsiasi momento di non ricevere tali offerte, se lo desiderate. I dati sono&hellip;  Read more","og_url":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/","og_site_name":"CATAccounting","article_modified_time":"2025-01-13T09:44:35+00:00","og_image":[{"width":657,"height":823,"url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/","url":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/","name":"Privacy Statement - CATAccounting","isPartOf":{"@id":"https:\/\/accounting-tax.co.th\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/#primaryimage"},"image":{"@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/#primaryimage"},"thumbnailUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png","datePublished":"2021-06-29T08:05:06+00:00","dateModified":"2025-01-13T09:44:35+00:00","breadcrumb":{"@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accounting-tax.co.th\/it\/privacy-statement\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/#primaryimage","url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png","contentUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-29.png"},{"@type":"BreadcrumbList","@id":"https:\/\/accounting-tax.co.th\/it\/privacy-statement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accounting-tax.co.th\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy Statement"}]},{"@type":"WebSite","@id":"https:\/\/accounting-tax.co.th\/it\/#website","url":"https:\/\/accounting-tax.co.th\/it\/","name":"CATAccounting","description":"","publisher":{"@id":"https:\/\/accounting-tax.co.th\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accounting-tax.co.th\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/accounting-tax.co.th\/it\/#organization","name":"CATAccounting","url":"https:\/\/accounting-tax.co.th\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/accounting-tax.co.th\/it\/#\/schema\/logo\/image\/","url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/cropped-logo-original-white.png","contentUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/cropped-logo-original-white.png","width":361,"height":220,"caption":"CATAccounting"},"image":{"@id":"https:\/\/accounting-tax.co.th\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/1112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/comments?post=1112"}],"version-history":[{"count":12,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/1112\/revisions"}],"predecessor-version":[{"id":2444,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/1112\/revisions\/2444"}],"wp:attachment":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/media?parent=1112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}