{"id":916,"date":"2021-06-28T08:27:04","date_gmt":"2021-06-28T08:27:04","guid":{"rendered":"https:\/\/cataccounting.ap5cnyhy-liquidwebsites.com\/our-clients\/"},"modified":"2021-09-13T04:32:05","modified_gmt":"2021-09-13T04:32:05","slug":"our-clients","status":"publish","type":"page","link":"https:\/\/accounting-tax.co.th\/it\/our-clients\/","title":{"rendered":"Our Clients"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"916\" class=\"elementor elementor-916\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c65ee75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c65ee75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29f3726\" data-id=\"29f3726\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b44a9a1 elementor-widget elementor-widget-spacer\" data-id=\"b44a9a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc6c93d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cc6c93d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63e3c54\" data-id=\"63e3c54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da8b2ee elementor-widget elementor-widget-image\" data-id=\"da8b2ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1214\" height=\"1059\" src=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png\" class=\"attachment-full size-full wp-image-917\" alt=\"\" srcset=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png 1214w, https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy-300x262.png 300w, https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy-1024x893.png 1024w, https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy-768x670.png 768w\" sizes=\"(max-width: 1214px) 100vw, 1214px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467615f head-box-our-clients elementor-widget elementor-widget-heading\" data-id=\"467615f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri clienti <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a3b4647 box-our-clients\" data-id=\"a3b4647\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3feee4 elementor-widget elementor-widget-text-editor\" data-id=\"c3feee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I nostri clienti soddisfatti sono i nostri migliori ambasciatori.<\/p><p>Dalle societ\u00e0 commerciali di medie dimensioni, al singolo pensionato, dall\u2019impresa abilitata ad operare dall\u2019Ente per lo sviluppo Industriale BOI, nella regione di Rayong e di Chonburi, agli investitori che cercano di garantire lo sviluppo della loro propriet\u00e0, i nostri clienti comprendono una vasta gamma di interessi di affari con un\u2019alta incidenza di elementi stranieri.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7e5e923 box-about-us\" data-id=\"7e5e923\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-655b40f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"655b40f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f0e814\" data-id=\"6f0e814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5947c6a elementor-widget elementor-widget-spacer\" data-id=\"5947c6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I nostri clienti I nostri clienti soddisfatti sono i nostri migliori ambasciatori. Dalle societ\u00e0 commerciali di medie dimensioni, al singolo pensionato, dall\u2019impresa abilitata ad operare dall\u2019Ente per lo sviluppo Industriale BOI, nella regione di Rayong e di Chonburi, agli investitori che cercano di garantire lo sviluppo della loro propriet\u00e0, i nostri clienti comprendono una vasta gamma di interessi di affari con un\u2019alta incidenza di elementi stranieri.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-916","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our Clients - CATAccounting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accounting-tax.co.th\/it\/our-clients\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Clients - CATAccounting\" \/>\n<meta property=\"og:description\" content=\"I nostri clienti I nostri clienti soddisfatti sono i nostri migliori ambasciatori. Dalle societ\u00e0 commerciali di medie dimensioni, al singolo pensionato, dall\u2019impresa abilitata ad operare dall\u2019Ente per lo sviluppo Industriale BOI, nella regione di Rayong e di Chonburi, agli investitori che cercano di garantire lo sviluppo della loro propriet\u00e0, i nostri clienti comprendono una vasta gamma di interessi di affari con un\u2019alta incidenza di elementi stranieri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accounting-tax.co.th\/it\/our-clients\/\" \/>\n<meta property=\"og:site_name\" content=\"CATAccounting\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-13T04:32:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/\",\"name\":\"Our Clients - CATAccounting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-26-Copy.png\",\"datePublished\":\"2021-06-28T08:27:04+00:00\",\"dateModified\":\"2021-09-13T04:32:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/#primaryimage\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-26-Copy.png\",\"contentUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Group-26-Copy.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/our-clients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Clients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\",\"name\":\"CATAccounting\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#organization\",\"name\":\"CATAccounting\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-logo-original-white.png\",\"contentUrl\":\"https:\\\/\\\/accounting-tax.co.th\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-logo-original-white.png\",\"width\":361,\"height\":220,\"caption\":\"CATAccounting\"},\"image\":{\"@id\":\"https:\\\/\\\/accounting-tax.co.th\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our Clients - CATAccounting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accounting-tax.co.th\/it\/our-clients\/","og_locale":"it_IT","og_type":"article","og_title":"Our Clients - CATAccounting","og_description":"I nostri clienti I nostri clienti soddisfatti sono i nostri migliori ambasciatori. Dalle societ\u00e0 commerciali di medie dimensioni, al singolo pensionato, dall\u2019impresa abilitata ad operare dall\u2019Ente per lo sviluppo Industriale BOI, nella regione di Rayong e di Chonburi, agli investitori che cercano di garantire lo sviluppo della loro propriet\u00e0, i nostri clienti comprendono una vasta gamma di interessi di affari con un\u2019alta incidenza di elementi stranieri.","og_url":"https:\/\/accounting-tax.co.th\/it\/our-clients\/","og_site_name":"CATAccounting","article_modified_time":"2021-09-13T04:32:05+00:00","og_image":[{"url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/","url":"https:\/\/accounting-tax.co.th\/it\/our-clients\/","name":"Our Clients - CATAccounting","isPartOf":{"@id":"https:\/\/accounting-tax.co.th\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/#primaryimage"},"image":{"@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/#primaryimage"},"thumbnailUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png","datePublished":"2021-06-28T08:27:04+00:00","dateModified":"2021-09-13T04:32:05+00:00","breadcrumb":{"@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accounting-tax.co.th\/it\/our-clients\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/#primaryimage","url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png","contentUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/Group-26-Copy.png"},{"@type":"BreadcrumbList","@id":"https:\/\/accounting-tax.co.th\/it\/our-clients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accounting-tax.co.th\/it\/"},{"@type":"ListItem","position":2,"name":"Our Clients"}]},{"@type":"WebSite","@id":"https:\/\/accounting-tax.co.th\/it\/#website","url":"https:\/\/accounting-tax.co.th\/it\/","name":"CATAccounting","description":"","publisher":{"@id":"https:\/\/accounting-tax.co.th\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accounting-tax.co.th\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/accounting-tax.co.th\/it\/#organization","name":"CATAccounting","url":"https:\/\/accounting-tax.co.th\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/accounting-tax.co.th\/it\/#\/schema\/logo\/image\/","url":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/cropped-logo-original-white.png","contentUrl":"https:\/\/accounting-tax.co.th\/wp-content\/uploads\/2021\/06\/cropped-logo-original-white.png","width":361,"height":220,"caption":"CATAccounting"},"image":{"@id":"https:\/\/accounting-tax.co.th\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/comments?post=916"}],"version-history":[{"count":16,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/916\/revisions"}],"predecessor-version":[{"id":1482,"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/pages\/916\/revisions\/1482"}],"wp:attachment":[{"href":"https:\/\/accounting-tax.co.th\/it\/wp-json\/wp\/v2\/media?parent=916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}